{"id":7847,"date":"2022-07-25T15:21:51","date_gmt":"2022-07-25T15:21:51","guid":{"rendered":"http:\/\/citywall.eu\/project\/einstein-boulderhalle-munchen\/"},"modified":"2022-07-28T10:03:45","modified_gmt":"2022-07-28T10:03:45","slug":"einstein-boulderhalle-munchen","status":"publish","type":"project","link":"https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/","title":{"rendered":"Einstein Boulderhalle Munchen"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"template":"","class_list":["post-7847","project","type-project","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Einstein Boulderhalle Munchen - Citywall.eu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einstein Boulderhalle Munchen - Citywall.eu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Citywall.eu\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-28T10:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/project\\\/einstein-boulderhalle-munchen\\\/\",\"url\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/project\\\/einstein-boulderhalle-munchen\\\/\",\"name\":\"Einstein Boulderhalle Munchen - Citywall.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/#website\"},\"datePublished\":\"2022-07-25T15:21:51+00:00\",\"dateModified\":\"2022-07-28T10:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/project\\\/einstein-boulderhalle-munchen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/citywall.eu\\\/fr\\\/project\\\/einstein-boulderhalle-munchen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/project\\\/einstein-boulderhalle-munchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/our-projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Einstein Boulderhalle Munchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/\",\"name\":\"Citywall.eu\",\"description\":\"Climbing Walls Manufacturer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/citywall.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einstein Boulderhalle Munchen - Citywall.eu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/","og_locale":"fr_FR","og_type":"article","og_title":"Einstein Boulderhalle Munchen - Citywall.eu","og_url":"https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/","og_site_name":"Citywall.eu","article_modified_time":"2022-07-28T10:03:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/","url":"https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/","name":"Einstein Boulderhalle Munchen - Citywall.eu","isPartOf":{"@id":"https:\/\/citywall.eu\/fr\/#website"},"datePublished":"2022-07-25T15:21:51+00:00","dateModified":"2022-07-28T10:03:45+00:00","breadcrumb":{"@id":"https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/citywall.eu\/fr\/project\/einstein-boulderhalle-munchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/citywall.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/citywall.eu\/fr\/our-projects\/"},{"@type":"ListItem","position":3,"name":"Einstein Boulderhalle Munchen"}]},{"@type":"WebSite","@id":"https:\/\/citywall.eu\/fr\/#website","url":"https:\/\/citywall.eu\/fr\/","name":"Citywall.eu","description":"Climbing Walls Manufacturer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/citywall.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/citywall.eu\/fr\/wp-json\/wp\/v2\/project\/7847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citywall.eu\/fr\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/citywall.eu\/fr\/wp-json\/wp\/v2\/types\/project"}],"wp:attachment":[{"href":"https:\/\/citywall.eu\/fr\/wp-json\/wp\/v2\/media?parent=7847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}